{"id":29134,"date":"2023-09-21T11:45:04","date_gmt":"2023-09-21T16:45:04","guid":{"rendered":"https:\/\/www.pruebasadk.com\/qrs\/product\/20-gauge-7-16-in-wide-crown-stapler\/"},"modified":"2023-10-18T16:29:48","modified_gmt":"2023-10-18T21:29:48","slug":"20-gauge-7-16-in-wide-crown-stapler","status":"publish","type":"product","link":"https:\/\/www.pruebasadk.com\/qrs\/product\/20-gauge-7-16-in-wide-crown-stapler\/","title":{"rendered":"20 Gauge 7\/16 in. Wide Crown Stapler"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":29401,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[615],"product_tag":[],"_links":{"self":[{"href":"https:\/\/www.pruebasadk.com\/qrs\/wp-json\/wp\/v2\/product\/29134"}],"collection":[{"href":"https:\/\/www.pruebasadk.com\/qrs\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.pruebasadk.com\/qrs\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pruebasadk.com\/qrs\/wp-json\/wp\/v2\/comments?post=29134"}],"version-history":[{"count":0,"href":"https:\/\/www.pruebasadk.com\/qrs\/wp-json\/wp\/v2\/product\/29134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pruebasadk.com\/qrs\/wp-json\/wp\/v2\/media\/29401"}],"wp:attachment":[{"href":"https:\/\/www.pruebasadk.com\/qrs\/wp-json\/wp\/v2\/media?parent=29134"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.pruebasadk.com\/qrs\/wp-json\/wp\/v2\/product_cat?post=29134"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.pruebasadk.com\/qrs\/wp-json\/wp\/v2\/product_tag?post=29134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}